{"id":4474,"date":"2022-02-08T10:38:28","date_gmt":"2022-02-08T10:38:28","guid":{"rendered":"https:\/\/maresalogistica.com\/blog\/palet-europeo-americano-medidas-diferencias\/"},"modified":"2022-03-16T09:38:56","modified_gmt":"2022-03-16T09:38:56","slug":"palet-europeo-americano-medidas-diferencias","status":"publish","type":"post","link":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/","title":{"rendered":"Palet europeo y palet americano: medidas y diferencias"},"content":{"rendered":"<p>Si est\u00e1s estudiando cu\u00e1l es la mejor forma de transportar tu mercanc\u00eda es posible que te hayas topado con dos t\u00e9rminos relevantes en esta aventura: <strong>palet europeo y palet americano<\/strong>. Hablamos de las principales alternativas que existen para almacenar la carga mientras viaja dentro del medio de transporte en cuesti\u00f3n. \u00bfQu\u00e9 <strong>diferencias hay entre uno y otro<\/strong>? Te contamos todos los detalles.<!--more--><\/p>\n<h2>Palet europeo<\/h2>\n<p>El palet europeo, tambi\u00e9n conocido como <strong>europalet o EPAL surgi\u00f3 para estandarizar las medidas<\/strong> de los palets utilizados en el transporte de mercanc\u00edas para aprovechar mejor el espacio. As\u00ed que, seg\u00fan la norma UNE-EN 13698-1 de \u00e1mbito europeo, se empezaron a utilizar todos los palets del mismo tama\u00f1o en Europa. Y, gracias a esta normalizaci\u00f3n,<strong> la manipulaci\u00f3n de las mercanc\u00edas es m\u00e1s sencilla<\/strong> y el transporte entre pa\u00edses se realiza con mayor fluidez.<\/p>\n<h3>Medidas del palet europeo<\/h3>\n<p>El palet europeo cuenta con unas <strong>medidas de 1.200 x 800 mm<\/strong> y est\u00e1 compuesto por tres patines y cuatro entradas de madera. La elecci\u00f3n de estas medidas no es fruto de la casualidad, sino que los valores son <strong>m\u00faltiplos de las dimensiones de gran cantidad de cajas de pl\u00e1stico est\u00e1ndar<\/strong>, lo que facilita que se puedan agrupar mercanc\u00edas y productos con mayor facilidad.<\/p>\n<p>Esta normalizaci\u00f3n ha hecho posible estandarizar el espacio de camiones y contenedores mar\u00edtimos. Por ejemplo, se conoce que los <strong>camiones tipo <em>trailer<\/em> equivalen a 33 palets europeos.<\/strong><\/p>\n<h3>\u00bfCu\u00e1nto peso aguanta un palet europeo?<\/h3>\n<p>El <strong>palet europeo<\/strong> se caracteriza por una gran resistencia a la carga: es capaz de soportar <strong>hasta 1.500 kg<\/strong> en movimiento y hasta 5.500 kg en reposo. A este peso, hab\u00eda que <strong>sumar el peso del propio palet europeo<\/strong>, que es de 25 kg.<\/p>\n<h2>Palet americano<\/h2>\n<p>El palet americano tambi\u00e9n es <strong>conocido como palet universal<\/strong> y sus or\u00edgenes se remontan a la segunda guerra mundial en Estados Unidos, momento en que el ej\u00e9rcito estadounidense realiza el dise\u00f1o del palet americano como sistema de carga. Se rige por la norma ISO 3676 y en nuestros d\u00edas es el m\u00e1s utilizado en Estados Unidos y Jap\u00f3n. Su estandarizaci\u00f3n <strong>ha facilitado enormemente el <a href=\"https:\/\/maresalogistica.com\/en\/services\/fast\/\">transporte internacional de mercanc\u00edas<\/a><\/strong>, del mismo modo que la normalizaci\u00f3n del palet europeo.<\/p>\n<h3>Medidas del palet americano<\/h3>\n<p>El palet americano cuenta con <strong>unas medidas de 1.200 x 1.000 mm.<\/strong> Como se puede observar tiene el mismo largo que el palet europeo pero<strong> el americano es un poco m\u00e1s ancho.<\/strong> El palet europeo tiene una apariencia m\u00e1s rectangular que el americano.<\/p>\n<h3>\u00bfCu\u00e1nto peso aguanta un palet americano?<\/h3>\n<p>El palet americano soporta <strong>una carga de hasta 1.200 kg<\/strong> en est\u00e1tico y de hasta 4.500 kg en movimiento. Y, a este peso, habr\u00eda que sumar el peso del propio palet, que son cerca de 25 kg.<\/p>\n<p>El palet americano <strong>tiene la particularidad de soportar especialmente bien las cargas din\u00e1micas<\/strong>, por lo que es habitual verlo en el transporte de sustancias l\u00edquidas.<\/p>\n<h2>\u00bf<strong>Palet europeo o americano<\/strong>? \u00bfCu\u00e1l es mejor?<\/h2>\n<p>La elecci\u00f3n de un palet u otro habitualmente no depende de nuestra elecci\u00f3n sino que <strong>depende de las caracter\u00edsticas del medio de transporte<\/strong> donde vaya a viajar la mercanc\u00eda. Por otro lado, <strong>los pa\u00edses de origen y de destino tambi\u00e9n pueden condicionar<\/strong> el tipo de palet donde vamos a almacenar nuestra mercanc\u00eda.<\/p>\n<p>Si tienes la oportunidad de elegir, es importante destacar que <strong>el europeo soporta m\u00e1s peso<\/strong>. Sin embargo, <strong>la organizaci\u00f3n del palet americano suele resultar m\u00e1s sencilla<\/strong> y con \u00e9l se aprovecha m\u00e1s el espacio normalmente.<\/p>\n<p><strong>Cualquiera de las dos opciones se puede manipular con facilidad<\/strong> mediante el uso de carretillas y, tanto el palet europeo como el americano resultan muy pr\u00e1cticas ante cualquier sistema de almacenaje, m\u00e1s todav\u00eda cuando se trata de almacenes autom\u00e1ticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s estudiando cu\u00e1l es la mejor forma de transportar tu mercanc\u00eda es posible que te hayas topado con dos t\u00e9rminos relevantes en esta aventura: palet europeo y palet americano. Hablamos de las principales alternativas que existen para almacenar la carga mientras viaja dentro del medio de transporte en cuesti\u00f3n. \u00bfQu\u00e9 diferencias hay entre uno &#8230; <a title=\"Palet europeo y palet americano: medidas y diferencias\" class=\"read-more\" href=\"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/\" aria-label=\"Read more about Palet europeo y palet americano: medidas y diferencias\">Read more<\/a><\/p>\n","protected":false},"author":3,"featured_media":4435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[31],"tags":[],"class_list":["post-4474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transportes-y-vehiculos-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica<\/title>\n<meta name=\"description\" content=\"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica\" \/>\n<meta property=\"og:description\" content=\"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Maresa Log\u00edstica\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T10:38:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-16T09:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/\"},\"author\":{\"name\":\"Jose L\u00f3pez\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#\\\/schema\\\/person\\\/42287fb767e017d20e72ba7536826508\"},\"headline\":\"Palet europeo y palet americano: medidas y diferencias\",\"datePublished\":\"2022-02-08T10:38:28+00:00\",\"dateModified\":\"2022-03-16T09:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/palet-europeo.jpg\",\"articleSection\":[\"Transportes y veh\u00edculos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/\",\"url\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/\",\"name\":\"Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/palet-europeo.jpg\",\"datePublished\":\"2022-02-08T10:38:28+00:00\",\"dateModified\":\"2022-03-16T09:38:56+00:00\",\"description\":\"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/palet-europeo.jpg\",\"contentUrl\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/palet-europeo.jpg\",\"width\":770,\"height\":514,\"caption\":\"Close up of Piles of different types of pallet at a recycling business area in HDR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/palet-europeo-americano-medidas-diferencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palet europeo y palet americano: medidas y diferencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/\",\"name\":\"Maresa Log\u00edstica\",\"description\":\"Operador log\u00edstico y de transportes\",\"publisher\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#organization\",\"name\":\"Maresa log\u00edstica > log\u00edstica y transportes a Baleares, Canarias, Ceuta y Melilla\",\"url\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-maresa-logistica-square-big.png\",\"contentUrl\":\"https:\\\/\\\/maresalogistica.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-maresa-logistica-square-big.png\",\"width\":420,\"height\":420,\"caption\":\"Maresa log\u00edstica > log\u00edstica y transportes a Baleares, Canarias, Ceuta y Melilla\"},\"image\":{\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/#\\\/schema\\\/person\\\/42287fb767e017d20e72ba7536826508\",\"name\":\"Jose L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g\",\"caption\":\"Jose L\u00f3pez\"},\"url\":\"https:\\\/\\\/maresalogistica.com\\\/en\\\/blog\\\/author\\\/jlopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica","description":"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/","og_locale":"en_US","og_type":"article","og_title":"Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica","og_description":"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?","og_url":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/","og_site_name":"Maresa Log\u00edstica","article_published_time":"2022-02-08T10:38:28+00:00","article_modified_time":"2022-03-16T09:38:56+00:00","og_image":[{"width":770,"height":514,"url":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg","type":"image\/jpeg"}],"author":"Jose L\u00f3pez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jose L\u00f3pez","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#article","isPartOf":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/"},"author":{"name":"Jose L\u00f3pez","@id":"https:\/\/maresalogistica.com\/en\/#\/schema\/person\/42287fb767e017d20e72ba7536826508"},"headline":"Palet europeo y palet americano: medidas y diferencias","datePublished":"2022-02-08T10:38:28+00:00","dateModified":"2022-03-16T09:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/"},"wordCount":661,"publisher":{"@id":"https:\/\/maresalogistica.com\/en\/#organization"},"image":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg","articleSection":["Transportes y veh\u00edculos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/","url":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/","name":"Diferencias entre el palet europeo y el americano - Maresa Log\u00edstica","isPartOf":{"@id":"https:\/\/maresalogistica.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#primaryimage"},"image":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg","datePublished":"2022-02-08T10:38:28+00:00","dateModified":"2022-03-16T09:38:56+00:00","description":"El palet europeo tiene unas caracter\u00edsticas diferentes al americano. Tambi\u00e9n tiene sus ventajas. \u00bfQuieres saber m\u00e1s sobre ellos?","breadcrumb":{"@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#primaryimage","url":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg","contentUrl":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2022\/02\/palet-europeo.jpg","width":770,"height":514,"caption":"Close up of Piles of different types of pallet at a recycling business area in HDR"},{"@type":"BreadcrumbList","@id":"https:\/\/maresalogistica.com\/en\/blog\/palet-europeo-americano-medidas-diferencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maresalogistica.com\/en\/"},{"@type":"ListItem","position":2,"name":"Palet europeo y palet americano: medidas y diferencias"}]},{"@type":"WebSite","@id":"https:\/\/maresalogistica.com\/en\/#website","url":"https:\/\/maresalogistica.com\/en\/","name":"Maresa Log\u00edstica","description":"Operador log\u00edstico y de transportes","publisher":{"@id":"https:\/\/maresalogistica.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maresalogistica.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maresalogistica.com\/en\/#organization","name":"Maresa log\u00edstica > log\u00edstica y transportes a Baleares, Canarias, Ceuta y Melilla","url":"https:\/\/maresalogistica.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maresalogistica.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2020\/02\/logo-maresa-logistica-square-big.png","contentUrl":"https:\/\/maresalogistica.com\/wp-content\/uploads\/2020\/02\/logo-maresa-logistica-square-big.png","width":420,"height":420,"caption":"Maresa log\u00edstica > log\u00edstica y transportes a Baleares, Canarias, Ceuta y Melilla"},"image":{"@id":"https:\/\/maresalogistica.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maresalogistica.com\/en\/#\/schema\/person\/42287fb767e017d20e72ba7536826508","name":"Jose L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21d3e65841e899c66580d0aa58de19d2516fb20a816068d045a9c6af0bb360e5?s=96&d=mm&r=g","caption":"Jose L\u00f3pez"},"url":"https:\/\/maresalogistica.com\/en\/blog\/author\/jlopez\/"}]}},"_links":{"self":[{"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/posts\/4474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/comments?post=4474"}],"version-history":[{"count":2,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/posts\/4474\/revisions"}],"predecessor-version":[{"id":4589,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/posts\/4474\/revisions\/4589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/media\/4435"}],"wp:attachment":[{"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/media?parent=4474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/categories?post=4474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maresalogistica.com\/en\/wp-json\/wp\/v2\/tags?post=4474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}